{"id":55936,"date":"2023-11-24T08:20:49","date_gmt":"2023-11-24T07:20:49","guid":{"rendered":"https:\/\/www.pauli.de\/?post_type=pauli-media&#038;p=55936"},"modified":"2023-11-24T08:20:49","modified_gmt":"2023-11-24T07:20:49","slug":"klemme-eckig-190","status":"publish","type":"pauli-media","link":"https:\/\/www.pauli.de\/sv\/pauli-media\/klemme-eckig-190\/","title":{"rendered":"Klemme, eckig"},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false},"pauli_db_categories":[448],"class_list":["post-55936","pauli-media","type-pauli-media","status-publish","hentry","pauli_db_categories-klemmbefestigungen"],"acf":[],"ACF":{"article_number":"9003ZN1","description":"Klemme, eckig","image":{"ID":55912,"id":55912,"title":"9003ZN1_PR","filename":"9003ZN1_PR.jpg","filesize":730524,"url":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR.jpg","link":"https:\/\/www.pauli.de\/sv\/9003zn1_pr-2\/","alt":"","author":"2008","description":"","caption":"","name":"9003zn1_pr-2","status":"inherit","uploaded_to":0,"date":"2023-11-24 07:01:54","modified":"2023-11-24 07:01:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.pauli.de\/wp-includes\/images\/media\/default.png","width":1800,"height":1800,"sizes":{"thumbnail":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-500x500.jpg","medium-width":500,"medium-height":500,"medium_large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-1200x1200.jpg","large-width":1200,"large-height":1200,"1536x1536":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-1536x1536.jpg","1536x1536-width":1536,"1536x1536-height":1536,"2048x2048":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR.jpg","2048x2048-width":1800,"2048x2048-height":1800,"widget":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-36x36.jpg","widget-width":36,"widget-height":36,"square":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-180x180.jpg","square-width":180,"square-height":180,"featured":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-1500x430.jpg","featured-width":1500,"featured-height":430,"featured_large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-1500x630.jpg","featured_large-width":1500,"featured_large-height":630,"extra_large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-1500x1500.jpg","extra_large-width":1500,"extra_large-height":1500,"portfolio":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-495x400.jpg","portfolio-width":495,"portfolio-height":400,"portfolio_small":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-260x185.jpg","portfolio_small-width":260,"portfolio_small-height":185,"gallery":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-845x684.jpg","gallery-width":845,"gallery-height":684,"magazine":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-710x375.jpg","magazine-width":710,"magazine-height":375,"masonry":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-705x705.jpg","masonry-width":705,"masonry-height":705,"entry_with_sidebar":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-845x321.jpg","entry_with_sidebar-width":845,"entry_with_sidebar-height":321,"entry_without_sidebar":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-1210x423.jpg","entry_without_sidebar-width":1210,"entry_without_sidebar-height":423}},"pauli_cloud_file_download":{"ID":55912,"id":55912,"title":"9003ZN1_PR","filename":"9003ZN1_PR.jpg","filesize":730524,"url":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR.jpg","link":"https:\/\/www.pauli.de\/sv\/9003zn1_pr-2\/","alt":"","author":"2008","description":"","caption":"","name":"9003zn1_pr-2","status":"inherit","uploaded_to":0,"date":"2023-11-24 07:01:54","modified":"2023-11-24 07:01:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.pauli.de\/wp-includes\/images\/media\/default.png","width":1800,"height":1800,"sizes":{"thumbnail":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-500x500.jpg","medium-width":500,"medium-height":500,"medium_large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-1200x1200.jpg","large-width":1200,"large-height":1200,"1536x1536":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-1536x1536.jpg","1536x1536-width":1536,"1536x1536-height":1536,"2048x2048":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR.jpg","2048x2048-width":1800,"2048x2048-height":1800,"widget":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-36x36.jpg","widget-width":36,"widget-height":36,"square":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-180x180.jpg","square-width":180,"square-height":180,"featured":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-1500x430.jpg","featured-width":1500,"featured-height":430,"featured_large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-1500x630.jpg","featured_large-width":1500,"featured_large-height":630,"extra_large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-1500x1500.jpg","extra_large-width":1500,"extra_large-height":1500,"portfolio":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-495x400.jpg","portfolio-width":495,"portfolio-height":400,"portfolio_small":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-260x185.jpg","portfolio_small-width":260,"portfolio_small-height":185,"gallery":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-845x684.jpg","gallery-width":845,"gallery-height":684,"magazine":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-710x375.jpg","magazine-width":710,"magazine-height":375,"masonry":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-705x705.jpg","masonry-width":705,"masonry-height":705,"entry_with_sidebar":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-845x321.jpg","entry_with_sidebar-width":845,"entry_with_sidebar-height":321,"entry_without_sidebar":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/11\/9003ZN1_PR-1210x423.jpg","entry_without_sidebar-width":1210,"entry_without_sidebar-height":423}},"type":{"value":"product","label":"Produkt"}},"_links":{"self":[{"href":"https:\/\/www.pauli.de\/sv\/wp-json\/wp\/v2\/pauli-media\/55936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauli.de\/sv\/wp-json\/wp\/v2\/pauli-media"}],"about":[{"href":"https:\/\/www.pauli.de\/sv\/wp-json\/wp\/v2\/types\/pauli-media"}],"wp:attachment":[{"href":"https:\/\/www.pauli.de\/sv\/wp-json\/wp\/v2\/media?parent=55936"}],"wp:term":[{"taxonomy":"pauli_db_categories","embeddable":true,"href":"https:\/\/www.pauli.de\/sv\/wp-json\/wp\/v2\/pauli_db_categories?post=55936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}