{"id":50300,"date":"2023-10-04T09:23:01","date_gmt":"2023-10-04T07:23:01","guid":{"rendered":"https:\/\/www.pauli.de\/?post_type=pauli-media&#038;p=50300"},"modified":"2023-10-04T09:23:01","modified_gmt":"2023-10-04T07:23:01","slug":"u-profil","status":"publish","type":"pauli-media","link":"https:\/\/www.pauli.de\/sv\/pauli-media\/u-profil\/","title":{"rendered":"U-Profil"},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false},"pauli_db_categories":[478],"class_list":["post-50300","pauli-media","type-pauli-media","status-publish","hentry","pauli_db_categories-walk-in"],"acf":[],"ACF":{"article_number":"8830E3\/50-2500","description":"U-Profil","image":{"ID":50304,"id":50304,"title":"8830_WP app","filename":"8830_WP-app.jpg","filesize":394520,"url":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app.jpg","link":"https:\/\/www.pauli.de\/sv\/8830_wp-app-2\/","alt":"","author":"3","description":"","caption":"","name":"8830_wp-app-2","status":"inherit","uploaded_to":0,"date":"2023-10-04 07:21:56","modified":"2023-10-04 07:21:56","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.pauli.de\/wp-includes\/images\/media\/default.png","width":886,"height":1181,"sizes":{"thumbnail":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-375x500.jpg","medium-width":375,"medium-height":500,"medium_large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app.jpg","large-width":886,"large-height":1181,"1536x1536":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app.jpg","1536x1536-width":886,"1536x1536-height":1181,"2048x2048":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app.jpg","2048x2048-width":886,"2048x2048-height":1181,"widget":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-36x36.jpg","widget-width":36,"widget-height":36,"square":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-180x180.jpg","square-width":180,"square-height":180,"featured":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-886x430.jpg","featured-width":886,"featured-height":430,"featured_large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-886x630.jpg","featured_large-width":886,"featured_large-height":630,"extra_large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app.jpg","extra_large-width":886,"extra_large-height":1181,"portfolio":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-495x400.jpg","portfolio-width":495,"portfolio-height":400,"portfolio_small":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-260x185.jpg","portfolio_small-width":260,"portfolio_small-height":185,"gallery":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-845x684.jpg","gallery-width":845,"gallery-height":684,"magazine":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-710x375.jpg","magazine-width":710,"magazine-height":375,"masonry":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-529x705.jpg","masonry-width":529,"masonry-height":705,"entry_with_sidebar":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-845x321.jpg","entry_with_sidebar-width":845,"entry_with_sidebar-height":321,"entry_without_sidebar":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-886x423.jpg","entry_without_sidebar-width":886,"entry_without_sidebar-height":423}},"pauli_cloud_file_download":{"ID":50304,"id":50304,"title":"8830_WP app","filename":"8830_WP-app.jpg","filesize":394520,"url":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app.jpg","link":"https:\/\/www.pauli.de\/sv\/8830_wp-app-2\/","alt":"","author":"3","description":"","caption":"","name":"8830_wp-app-2","status":"inherit","uploaded_to":0,"date":"2023-10-04 07:21:56","modified":"2023-10-04 07:21:56","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.pauli.de\/wp-includes\/images\/media\/default.png","width":886,"height":1181,"sizes":{"thumbnail":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-375x500.jpg","medium-width":375,"medium-height":500,"medium_large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app.jpg","large-width":886,"large-height":1181,"1536x1536":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app.jpg","1536x1536-width":886,"1536x1536-height":1181,"2048x2048":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app.jpg","2048x2048-width":886,"2048x2048-height":1181,"widget":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-36x36.jpg","widget-width":36,"widget-height":36,"square":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-180x180.jpg","square-width":180,"square-height":180,"featured":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-886x430.jpg","featured-width":886,"featured-height":430,"featured_large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-886x630.jpg","featured_large-width":886,"featured_large-height":630,"extra_large":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app.jpg","extra_large-width":886,"extra_large-height":1181,"portfolio":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-495x400.jpg","portfolio-width":495,"portfolio-height":400,"portfolio_small":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-260x185.jpg","portfolio_small-width":260,"portfolio_small-height":185,"gallery":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-845x684.jpg","gallery-width":845,"gallery-height":684,"magazine":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-710x375.jpg","magazine-width":710,"magazine-height":375,"masonry":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-529x705.jpg","masonry-width":529,"masonry-height":705,"entry_with_sidebar":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-845x321.jpg","entry_with_sidebar-width":845,"entry_with_sidebar-height":321,"entry_without_sidebar":"https:\/\/www.pauli.de\/wp-content\/uploads\/2023\/10\/8830_WP-app-886x423.jpg","entry_without_sidebar-width":886,"entry_without_sidebar-height":423}},"type":{"value":"product","label":"Produkt"}},"_links":{"self":[{"href":"https:\/\/www.pauli.de\/sv\/wp-json\/wp\/v2\/pauli-media\/50300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pauli.de\/sv\/wp-json\/wp\/v2\/pauli-media"}],"about":[{"href":"https:\/\/www.pauli.de\/sv\/wp-json\/wp\/v2\/types\/pauli-media"}],"wp:attachment":[{"href":"https:\/\/www.pauli.de\/sv\/wp-json\/wp\/v2\/media?parent=50300"}],"wp:term":[{"taxonomy":"pauli_db_categories","embeddable":true,"href":"https:\/\/www.pauli.de\/sv\/wp-json\/wp\/v2\/pauli_db_categories?post=50300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}